{"id":1668,"date":"2020-08-02T10:41:36","date_gmt":"2020-08-02T09:41:36","guid":{"rendered":"https:\/\/www.unitedpeople.online\/politique-de-cookies\/"},"modified":"2020-10-22T09:55:26","modified_gmt":"2020-10-22T07:55:26","slug":"politique-de-cookies","status":"publish","type":"page","link":"https:\/\/www.unitedpeople.online\/en\/politique-de-cookies\/","title":{"rendered":"Politique de cookies"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1596124459801{background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221; el_class=&#8221;header_empty_space&#8221;][vc_column][vc_empty_space height=&#8221;90px&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1596124508728{background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221; el_class=&#8221;title_header_bg&#8221;][vc_column][vc_column_text]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">POLITIQUE DE COOKIES<\/span><\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h3><strong>Centre des pr\u00e9f\u00e9rences<\/strong><\/h3>\n<p><strong>Votre confidentialit\u00e9<\/strong><\/p>\n<p>Sauf pour les cookies et technologies similaires {\u00ab\u202fCookies\u202f\u00bb} qui sont strictement n\u00e9cessaires au fonctionnement du site internet, vous pouvez accepter ou refuser que nous utilisions des Cookies pour chaque finalit\u00e9 distincte ci-dessous mentionn\u00e9e, en d\u00e9pla\u00e7ant le curseur \u00e0 la fin de chaque ligne. Chaque fois qu\u2019il vous est donn\u00e9 la possibilit\u00e9 d\u2019accepter ou de refuser l\u2019utilisation de Cookies, nous vous fournissons les informations essentielles afin de vous permettre de faire votre choix : l\u2019objectif du traitement, le Cookie ou la cat\u00e9gorie de Cookies utilis\u00e9{s}, l\u2019identit\u00e9 du responsable de traitement, les types de donn\u00e9es personnelles recueillies et utilis\u00e9es et le transfert \u00e9ventuel de vos donn\u00e9es personnelles hors de l\u2019Espace Economique Europ\u00e9en. Une fois que vous nous avez donn\u00e9 votre accord concernant l\u2019utilisation de Cookies pour une finalit\u00e9, vous pouvez revenir sur votre choix, \u00e0 tout moment, en d\u00e9pla\u00e7ant le curseur \u00e0 la fin de la ligne concern\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Cookies strictement n\u00e9cessaires<\/strong><\/h3>\n<p><strong>Toujours actif<\/strong><\/p>\n<p>Ces cookies sont indispensables au bon fonctionnement du site web et ne peuvent pas \u00eatre d\u00e9sactiv\u00e9s de nos syst\u00e8mes. Ils ne sont g\u00e9n\u00e9ralement qu&#8217;activ\u00e9s en r\u00e9ponse \u00e0 des actions que vous effectuez et qui correspondent \u00e0 une demande de services, comme la configuration de vos pr\u00e9f\u00e9rences de confidentialit\u00e9, la connexion ou le remplissage de formulaires. Vous pouvez configurer votre navigateur pour bloquer ou \u00eatre alert\u00e9 de l&#8217;utilisation de ces cookies. Cependant, si cette cat\u00e9gorie de cookies &#8211; qui ne stocke aucune donn\u00e9e personnelle &#8211; est bloqu\u00e9e, certaines parties du site ne pourront pas fonctionner.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Cookies utilis\u00e9s<\/strong><\/h3>\n<p><strong>Cookies de performance<\/strong><\/p>\n<p>Ces cookies nous permettent de d\u00e9terminer le nombre de visites et les sources du trafic sur notre site web, afin d&#8217;en mesurer et d\u2019en am\u00e9liorer les performances. Ils nous aident \u00e9galement \u00e0 identifier les pages les plus \/ moins visit\u00e9es et \u00e0 \u00e9valuer comment les visiteurs naviguent sur le site. Toutes les informations, collect\u00e9es par ces cookies, sont agr\u00e9g\u00e9es et donc anonymis\u00e9es. Si vous n&#8217;acceptez pas cette cat\u00e9gorie de cookies, nous ne pourrons pas savoir quand vous avez r\u00e9alis\u00e9 votre visite sur notre site web.<\/p>\n<p><strong>Cookies utilis\u00e9s<\/strong><\/p>\n<p>_ga, _gat_UA-174178230-1, _gid, AKA_A2<\/p>\n<p><strong>Cookies pour une publicit\u00e9 cibl\u00e9e<\/strong><\/p>\n<p>Ces cookies peuvent \u00eatre activ\u00e9s sur notre site web par nos partenaires publicitaires. Ils peuvent \u00eatre utilis\u00e9s par ces entreprises pour \u00e9tablir des profils sur vos int\u00e9r\u00eats, et afin de vous proposer des publicit\u00e9s cibl\u00e9es sur d\u2019autres sites. Ils fonctionnement uniquement en identifiant votre navigateur et votre appareil. Si vous n&#8217;acceptez pas cette cat\u00e9gorie de cookies, des publicit\u00e9s moins cibl\u00e9es sur vos int\u00e9r\u00eats vous seront propos\u00e9es lors de votre navigation sur d&#8217;autres sites web.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1596124459801{background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221; el_class=&#8221;header_empty_space&#8221;][vc_column][vc_empty_space height=&#8221;90px&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1596124508728{background-position: 0 0 !important;background-repeat: no-repeat<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-1668","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/pages\/1668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/comments?post=1668"}],"version-history":[{"count":1,"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/pages\/1668\/revisions"}],"predecessor-version":[{"id":1672,"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/pages\/1668\/revisions\/1672"}],"wp:attachment":[{"href":"https:\/\/www.unitedpeople.online\/en\/wp-json\/wp\/v2\/media?parent=1668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}